{"id":7114,"count":1,"description":"","link":"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/","name":"TransdJabodetabek","slug":"transdjabodetabek","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TransdJabodetabek Archives - Buka Berita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TransdJabodetabek Archives - Buka Berita\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/\" \/>\n<meta property=\"og:site_name\" content=\"Buka Berita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/\",\"url\":\"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/\",\"name\":\"TransdJabodetabek Archives - Buka Berita\",\"isPartOf\":{\"@id\":\"https:\/\/bukaberita.co.id\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bukaberita.co.id\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TransdJabodetabek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bukaberita.co.id\/#website\",\"url\":\"https:\/\/bukaberita.co.id\/\",\"name\":\"Buka Berita\",\"description\":\"Tagline DIsini\",\"publisher\":{\"@id\":\"https:\/\/bukaberita.co.id\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bukaberita.co.id\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bukaberita.co.id\/#organization\",\"name\":\"Buka Berita\",\"url\":\"https:\/\/bukaberita.co.id\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\/\/bukaberita.co.id\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bukaberita.co.id\/wp-content\/uploads\/2024\/04\/LOGO-3.png\",\"contentUrl\":\"https:\/\/bukaberita.co.id\/wp-content\/uploads\/2024\/04\/LOGO-3.png\",\"width\":513,\"height\":513,\"caption\":\"Buka Berita\"},\"image\":{\"@id\":\"https:\/\/bukaberita.co.id\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TransdJabodetabek Archives - Buka Berita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/","og_locale":"id_ID","og_type":"article","og_title":"TransdJabodetabek Archives - Buka Berita","og_url":"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/","og_site_name":"Buka Berita","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/","url":"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/","name":"TransdJabodetabek Archives - Buka Berita","isPartOf":{"@id":"https:\/\/bukaberita.co.id\/#website"},"breadcrumb":{"@id":"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/bukaberita.co.id\/index.php\/tag\/transdjabodetabek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bukaberita.co.id\/"},{"@type":"ListItem","position":2,"name":"TransdJabodetabek"}]},{"@type":"WebSite","@id":"https:\/\/bukaberita.co.id\/#website","url":"https:\/\/bukaberita.co.id\/","name":"Buka Berita","description":"Tagline DIsini","publisher":{"@id":"https:\/\/bukaberita.co.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bukaberita.co.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/bukaberita.co.id\/#organization","name":"Buka Berita","url":"https:\/\/bukaberita.co.id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/bukaberita.co.id\/#\/schema\/logo\/image\/","url":"https:\/\/bukaberita.co.id\/wp-content\/uploads\/2024\/04\/LOGO-3.png","contentUrl":"https:\/\/bukaberita.co.id\/wp-content\/uploads\/2024\/04\/LOGO-3.png","width":513,"height":513,"caption":"Buka Berita"},"image":{"@id":"https:\/\/bukaberita.co.id\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bukaberita.co.id\/index.php\/wp-json\/wp\/v2\/tags\/7114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bukaberita.co.id\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bukaberita.co.id\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bukaberita.co.id\/index.php\/wp-json\/wp\/v2\/posts?tags=7114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}